{"id":1367,"date":"2009-10-06T10:57:59","date_gmt":"2009-10-06T10:57:59","guid":{"rendered":"https:\/\/www.deedeeparis.com\/wordpress\/1542-les-malentendus-de-benoit-duteurtre"},"modified":"2009-10-06T10:57:59","modified_gmt":"2009-10-06T10:57:59","slug":"les-malentendus-de-benoit-duteurtre","status":"publish","type":"post","link":"https:\/\/www.deedeeparis.com\/blog\/les-malentendus-de-benoit-duteurtre","title":{"rendered":"Les Malentendus de Beno\u00eet Duteurtre"},"content":{"rendered":"<p><img decoding=\"async\" src=\"\/blog\/images\/Culture confiture\/les-malentendus.jpg\" alt=\"\" style=\"float:left; margin: 0 1em 1em 0;\" \/>On m&rsquo;avait tellement souvent vant\u00e9 les m\u00e9rites de Beno\u00eet Duteurtre que j&rsquo;ai fini par succomber. Bien m&rsquo;en a pris&nbsp;!<\/p>\n<p><em>Les Malentendus<\/em>, c&rsquo;est l&rsquo;histoire de C\u00e9cile, jeune cr\u00e9atrice d&rsquo;entreprise de droite convaincue, de Martin, un \u00e9tudiant de gauche militant s&rsquo;appr\u00eatant \u00e0 r\u00e9diger un manifeste en faveur des sans-papiers, de Rachid et Karim, deux cousins \u00ab\u00a0rebeus\u00a0\u00bb, l&rsquo;un n\u00e9 en France, l&rsquo;autre immigr\u00e9 sans papier et de Jean-Robert, un handicap\u00e9 qui vit en banlieue.<\/p>\n<p>Tout ce beau petit monde n&rsquo;\u00e9tant bien entendu pas fait pour se rencontrer, il vont tous avoir \u00e0 faire l&rsquo;un \u00e0 l&rsquo;autre \u00e0 un moment de l&rsquo;histoire. Un r\u00e9cit social duquel se d\u00e9gage une tension qui va crescendo et qui se d\u00e9noue sur cette conclusion&nbsp;: m\u00e9fions-nous de nos id\u00e9es re\u00e7ues et de nos bons sentiments.<\/p>\n<p><img decoding=\"async\" src=\"\/blog\/images\/Admin\/monavis-TRES BON.bmp\" alt=\"\" \/><\/p>\n<p>J&rsquo;ai beaucoup, beaucoup aim\u00e9 ce r\u00e9cit. Court, impactant, bien men\u00e9&nbsp;: la plume de Beno\u00eet Duteurtre sert \u00e0 merveille le propos.<\/p>\n<p><strong>Ce que dit la 4\u00e8me de couv&rsquo; :<\/strong> <em>Un \u00e9tudiant de gauche. Une jeune femme de droite. Un immigr\u00e9 clandestin et son cousin, n\u00e9 en France. Un handicap\u00e9 de la route&#8230; Construit comme une pi\u00e8ce de th\u00e9\u00e2tre, ce r\u00e9cit met face \u00e0 face quelques personnages qui n&rsquo;auraient pas d\u00fb se rencontrer&nbsp;: leurs dialogues probl\u00e9matiques et leurs rapprochements inattendus, sur fond de manifestation pour les sans-papiers. Un vieux caf\u00e9 de la Goutte-d&rsquo;Or. Un fauteuil roulant informatis\u00e9 devenu incontr\u00f4lable, et d&rsquo;autres r\u00eaves qui se d\u00e9r\u00e8glent.<\/em><\/p>\n<p><em>Des zones suburbaines aux parcs de loisirs, \u00e9pisodes burlesques et situations sociales s&rsquo;enchev\u00eatrent dans un perp\u00e9tuel malentendu.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p><img decoding=\"async\" src=\"\/blog\/images\/Culture confiture\/les-malentendus.jpg\" alt=\"\" style=\"float:left; margin: 0 1em 1em 0;\" \/>On m&rsquo;avait tellement souvent vant\u00e9 les m\u00e9rites de Beno\u00eet Duteurtre que j&rsquo;ai fini par succomber. Bien m&rsquo;en a pris&nbsp;!<\/p>\n<p><em>Les Malentendus<\/em>, c&rsquo;est l&rsquo;histoire de C\u00e9cile, jeune cr\u00e9atrice d&rsquo;entreprise de droite convaincue, de Martin, un \u00e9tudiant de gauche militant s&rsquo;appr\u00eatant \u00e0 r\u00e9diger un manifeste en faveur des sans-papiers, de Rachid et Karim, deux cousins \u00ab\u00a0rebeus\u00a0\u00bb, l&rsquo;un n\u00e9 en France, l&rsquo;autre immigr\u00e9 sans papier et de Jean-Robert, un handicap\u00e9 qui vit en banlieue.<\/p>\n<p>Tout ce beau petit monde n&rsquo;\u00e9tant bien entendu pas fait pour se rencontrer, il vont tous avoir \u00e0 faire l&rsquo;un \u00e0 l&rsquo;autre \u00e0 un moment de l&rsquo;histoire. Un r\u00e9cit social duquel se d\u00e9gage une tension qui va crescendo et qui se d\u00e9noue sur cette conclusion&nbsp;: m\u00e9fions-nous de nos id\u00e9es re\u00e7ues et de nos bons sentiments.<\/p>\n<p><img decoding=\"async\" src=\"\/blog\/images\/Admin\/monavis-TRES BON.bmp\" alt=\"\" \/><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[2393,2391,1461,1513,2392],"class_list":["post-1367","post","type-post","status-publish","format-standard","hentry","category-culture-confiture","tag-benoit-duteurtre","tag-les-malentendus-de-benoit-duteurtre","tag-livres-a-lire","tag-pal","tag-pile-a-lire"],"acf":[],"geo":null,"_links":{"self":[{"href":"https:\/\/www.deedeeparis.com\/blog\/wp-json\/wp\/v2\/posts\/1367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deedeeparis.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deedeeparis.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deedeeparis.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deedeeparis.com\/blog\/wp-json\/wp\/v2\/comments?post=1367"}],"version-history":[{"count":0,"href":"https:\/\/www.deedeeparis.com\/blog\/wp-json\/wp\/v2\/posts\/1367\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.deedeeparis.com\/blog\/wp-json\/wp\/v2\/media?parent=1367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deedeeparis.com\/blog\/wp-json\/wp\/v2\/categories?post=1367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deedeeparis.com\/blog\/wp-json\/wp\/v2\/tags?post=1367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}