{"id":3507,"count":1,"description":"","link":"https:\/\/www.deedeeparis.com\/blog\/tag\/parisiennes-a-paris","name":"parisiennes \u00e0 paris","slug":"parisiennes-a-paris","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/www.deedeeparis.com\/blog\/wp-json\/wp\/v2\/tags\/3507","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deedeeparis.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.deedeeparis.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.deedeeparis.com\/blog\/wp-json\/wp\/v2\/posts?tags=3507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}